{"id":1173,"date":"2026-05-28T07:04:53","date_gmt":"2025-10-22T09:29:09","guid":{"rendered":"https:\/\/www.centralmotors.it\/toyota\/veicoli\/toyota-aygo-x\/nuova-toyota-aygo-x-1-5-hybrid-premium-e-cvt-a-torino\/"},"modified":"2026-05-28T10:04:53","modified_gmt":"2026-05-28T08:04:53","slug":"nuova-toyota-aygo-x-1-5-hybrid-premium-e-cvt-a-torino","status":"publish","type":"veicoli","link":"https:\/\/www.centralmotors.it\/toyota\/veicoli\/toyota-aygo-x-2\/nuova-toyota-aygo-x-1-5-hybrid-premium-e-cvt-a-torino\/","title":{"rendered":"Nuova Toyota Aygo X 1.5 hybrid Premium e-cvt a Torino"},"content":{"rendered":"<\/ul>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Toyota Aygo X 1.5 hybrid Premium e-cvt<\/p>\n","protected":false},"featured_media":0,"parent":1170,"menu_order":2,"template":"","veicoli_modello":[3,2],"veicoli_tipologia":[5],"veicoli_alimentazione":[12],"veicoli_promozione":[],"veicoli_cambio":[8],"veicoli_carrozzeria":[7],"veicoli_tag":[],"veicoli_sede":[],"class_list":["post-1173","veicoli","type-veicoli","status-publish","hentry","veicoli_modello-aygo-x","veicoli_modello-toyota","veicoli_tipologia-nuovo","veicoli_alimentazione-ibrido-benzina","veicoli_cambio-cvt","veicoli_carrozzeria-crossover"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli"}],"about":[{"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/types\/veicoli"}],"version-history":[{"count":0,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli\/1173\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli\/1170"}],"wp:attachment":[{"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"veicoli_modello","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_modello?post=1173"},{"taxonomy":"veicoli_tipologia","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_tipologia?post=1173"},{"taxonomy":"veicoli_alimentazione","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_alimentazione?post=1173"},{"taxonomy":"veicoli_promozione","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_promozione?post=1173"},{"taxonomy":"veicoli_cambio","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_cambio?post=1173"},{"taxonomy":"veicoli_carrozzeria","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_carrozzeria?post=1173"},{"taxonomy":"veicoli_tag","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_tag?post=1173"},{"taxonomy":"veicoli_sede","embeddable":true,"href":"https:\/\/www.centralmotors.it\/toyota\/wp-json\/wp\/v2\/veicoli_sede?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}