{"id":5530,"date":"2026-05-13T07:30:19","date_gmt":"2026-05-09T05:30:22","guid":{"rendered":"https:\/\/www.centralmotors.it\/usato\/veicoli\/jeep-renegade-1-6-mjt-limited-2wd-130cv-diesel-usata-u_1066168\/"},"modified":"2026-05-13T09:30:19","modified_gmt":"2026-05-13T07:30:19","slug":"jeep-renegade-1-6-mjt-limited-2wd-130cv-diesel-usata-u_1066168","status":"publish","type":"veicoli","link":"https:\/\/www.centralmotors.it\/usato\/veicoli\/jeep-renegade-1-6-mjt-limited-2wd-130cv-diesel-usata-u_1066168\/","title":{"rendered":"Jeep Renegade 1.6 Mjt Limited 2wd 130cv Diesel Usata"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Jeep Renegade 1.6 Mjt Limited 2wd 130cv Diesel Usata<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","veicoli_modello":[41,76],"veicoli_tipologia":[8],"veicoli_alimentazione":[18],"veicoli_promozione":[],"veicoli_cambio":[7],"veicoli_carrozzeria":[15],"veicoli_tag":[11],"veicoli_sede":[385],"class_list":["post-5530","veicoli","type-veicoli","status-publish","hentry","veicoli_modello-jeep","veicoli_modello-renegade","veicoli_tipologia-usato","veicoli_alimentazione-diesel","veicoli_cambio-manuale","veicoli_carrozzeria-suv","veicoli_tag-neopatentati","veicoli_sede-385"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli\/5530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli"}],"about":[{"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/types\/veicoli"}],"version-history":[{"count":0,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli\/5530\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/media?parent=5530"}],"wp:term":[{"taxonomy":"veicoli_modello","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_modello?post=5530"},{"taxonomy":"veicoli_tipologia","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_tipologia?post=5530"},{"taxonomy":"veicoli_alimentazione","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_alimentazione?post=5530"},{"taxonomy":"veicoli_promozione","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_promozione?post=5530"},{"taxonomy":"veicoli_cambio","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_cambio?post=5530"},{"taxonomy":"veicoli_carrozzeria","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_carrozzeria?post=5530"},{"taxonomy":"veicoli_tag","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_tag?post=5530"},{"taxonomy":"veicoli_sede","embeddable":true,"href":"https:\/\/www.centralmotors.it\/usato\/wp-json\/wp\/v2\/veicoli_sede?post=5530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}